{"id":19569,"date":"2021-04-21T13:20:11","date_gmt":"2021-04-21T13:20:11","guid":{"rendered":"https:\/\/pluschem.com\/join-pluschem\/"},"modified":"2023-01-17T12:17:33","modified_gmt":"2023-01-17T12:17:33","slug":"join-pluschem","status":"publish","type":"page","link":"https:\/\/dev.pluschem.com\/tr\/join-pluschem\/","title":{"rendered":"PLUSCHEM\u2019E KATILIN"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19569\" class=\"elementor elementor-19569 elementor-646\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a309732 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-content-middle elementor-section-height-default\" data-id=\"1a309732\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-867e5b6\" data-id=\"867e5b6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77f4224 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77f4224\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-166e432\" data-id=\"166e432\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-688da06 elementor-widget elementor-widget-spacer\" data-id=\"688da06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dfe1de8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dfe1de8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b6de921\" data-id=\"b6de921\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58c0b28b elementor-widget elementor-widget-heading\" data-id=\"58c0b28b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PlusChem - Kendini Kan\u0131tlam\u0131\u015f bir Uzmanla \u00c7al\u0131\u015f\u0131n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70056e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70056e9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f8d7fa\" data-id=\"5f8d7fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a8118e9 elementor-widget elementor-widget-spacer\" data-id=\"a8118e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-80ecb81 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"80ecb81\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-109478d\" data-id=\"109478d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86dca40 elementor-widget elementor-widget-text-editor\" data-id=\"86dca40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PlusChem d\u00fcnyan\u0131n \u00f6nc\u00fc kimyasal distrib\u00fct\u00f6r a\u011flar\u0131ndan biridir ve bizimle \u00e7al\u0131\u015fmak hem tedarik\u00e7ilere hem de yeni ortaklara bir\u00e7ok avantaj sunuyor. K\u00fcresel olarak 21 \u00fclkede faaliyet g\u00f6stererek, ila\u00e7, g\u0131da, yem, kozmetik, zirai ila\u00e7, end\u00fcstriyel, t\u0131bbi polimer, kaplama, yap\u0131\u015ft\u0131r\u0131c\u0131 ve kau\u00e7uk dahil olmak \u00fczere ana sanayilerde uluslararas\u0131 olarak ortaklar\u0131m\u0131zla \u00e7al\u0131\u015f\u0131yoruz.<\/p><p>Gelecek y\u0131llarda, k\u00fcresel olarak yeni \u00fcreticilerle yak\u0131ndan \u00e7al\u0131\u015fmay\u0131 ve tabii yeni ortaklar\u0131 a\u011f\u0131m\u0131za dahil etmeyi sab\u0131rs\u0131zl\u0131kla bekliyoruz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-03f7099\" data-id=\"03f7099\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-64ed15b elementor-widget elementor-widget-image\" data-id=\"64ed15b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/10\/PlusChem-a-chemical-specialist-1000x650-1.jpg\" title=\"PlusChem &#8211; a chemical specialist\" alt=\"PlusChem - a chemical specialist\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84bd0c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84bd0c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-208fd11\" data-id=\"208fd11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8055721 elementor-widget elementor-widget-spacer\" data-id=\"8055721\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13739a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13739a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dcd38de\" data-id=\"dcd38de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89c2d7b elementor-widget elementor-widget-tp-switcher\" data-id=\"89c2d7b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tp-switcher.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"switch6a04607bd1a71\" class=\"theplus-switcher switch-1 \"  data-id=\"switch6a04607bd1a71\" ><div class=\"switcher-toggle inactive center style-2\"><div class=\"switch-1\" ><h5 class=\"switch-label-text switch-label-1\">Tedarik\u00e7iler<\/h5>\r\n\t\t\t\t\t\t\r\n\t\t\t<\/div><div class=\"switcher-button\" data-type=\"style-2\"><label class=\"switch-label-btn\"><input class=\"switch-toggle round-style-2\" type=\"checkbox\"><span class=\"switch-slider style-2 switch-round\"><\/span><\/label><\/div><div class=\"switch-2\" ><h5 class=\"switch-label-text switch-label-2\">ortaklar<\/h5>\r\n\t\t\t\r\n\t\t\t<\/div><\/div><div class=\"switcher-toggle-sections\"><div class=\"switcher-section-1\" style=\"display: block;\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"19574\" class=\"elementor elementor-19574 elementor-4342\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f1ca09f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1ca09f\" data-element_type=\"section\" data-e-type=\"section\" id=\"suppliers-section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d48d73c\" data-id=\"7d48d73c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f5c50b3 elementor-widget elementor-widget-heading\" data-id=\"4f5c50b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tedarik\u00e7iler ve \u00fcreticiler i\u00e7in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2eb38867 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2eb38867\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-42dfe16e\" data-id=\"42dfe16e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59078058 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"59078058\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"217.88\" height=\"218.03\" viewBox=\"0 0 217.88 218.03\"><path d=\"M136.14,0,132.8,20.5a50.88,50.88,0,0,0-7.66,3.14L108.23,11.56,90.94,28.85l11.89,17A50.94,50.94,0,0,0,99.6,53.6L79.19,57V81.44l20.38,3.61a50.67,50.67,0,0,0,3.22,7.74l-12,16.86L108,126.94l17-11.91a52,52,0,0,0,7.7,3.18l3.41,20.5h24.45l3.64-20.56a51.85,51.85,0,0,0,7.68-3.21l17.1,12,17.31-17.3-12.23-17a51.85,51.85,0,0,0,3.13-7.58l20.64-3.62V57L197.22,53.6A50.5,50.5,0,0,0,194.08,46l12-17.14-17.29-17.3L171.87,23.74a51.37,51.37,0,0,0-7.65-3.18L160.62,0Zm-47,1.41a4.76,4.76,0,0,0-.84.07C64.67,5.15,48.47,15.82,38.19,30.28c-10,14.11-14.45,31.51-16.5,49.38L1.63,114.23l0,0a13.06,13.06,0,0,0,5,17.61l.1.05,15.14,7.57,4.88,35.71v.06c2.12,13.28,13.76,23.4,27.25,22.86l15.33,0V218H73.4A4.89,4.89,0,0,0,75,218h4.17V188.24l-25.53,0h-.11c-8.25.33-15.72-6.06-17.07-14.52v.12L30.92,133l-19.53-9.76a2.78,2.78,0,0,1-1.12-4.13l20.91-36,.11-1c1.87-17.41,6.16-33.58,15-46S68.33,14.61,89.86,11.27a5,5,0,0,0-.69-9.86Zm55.4,8.5h7.73l3.17,18.14,3.12.78A41.41,41.41,0,0,1,170,33.58l2.8,1.69,14.94-10.75L193.22,30,182.6,45.14l1.65,2.76A41.31,41.31,0,0,1,189,59.25l.79,3.17,18.22,3v7.72l-18.23,3.21L189,79.45a41,41,0,0,1-4.7,11.36l-1.67,2.8,10.78,15-5.46,5.47-15.13-10.62L170,105.12a41.68,41.68,0,0,1-11.4,4.77l-3.09.78-3.21,18.13h-7.75l-3-18.08-3.17-.78a41.81,41.81,0,0,1-11.45-4.73l-2.76-1.67-15,10.52-5.48-5.48,10.64-14.87-1.7-2.78a41.41,41.41,0,0,1-4.77-11.49l-.77-3.12-18-3.18V65.38l18-3,.79-3.14a41.89,41.89,0,0,1,4.77-11.51L114.32,45,103.83,30l5.47-5.48,14.9,10.65L127,33.47a41.42,41.42,0,0,1,11.44-4.7l3.19-.77Zm4,34.68A24.77,24.77,0,1,0,173.3,69.35,24.84,24.84,0,0,0,148.53,44.59Zm0,9.9a14.86,14.86,0,1,1-14.86,14.86A14.79,14.79,0,0,1,148.53,54.49Zm29.74,82.39a4.93,4.93,0,0,0-4.07,2.18c-9.62,13.73-15.68,29.92-15.68,47.17v21.82h-.08V218h4.2a4.83,4.83,0,0,0,1.61,0h4.1v-4a4.86,4.86,0,0,0,.07-.93V186.23c0-14.92,5.24-29.15,13.89-41.49a5,5,0,0,0-4-7.86Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7342c4e9 elementor-widget elementor-widget-heading\" data-id=\"7342c4e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Uzmanl\u0131k<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44b42193 elementor-widget elementor-widget-text-editor\" data-id=\"44b42193\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ge\u00e7en yirmi y\u0131l boyunca geli\u015fen \u00f6zellikli kimyasal ticareti uzmanl\u0131\u011f\u0131na sahibiz, payda\u015flar\u0131m\u0131z \u00e7ok daha uzun y\u0131llard\u0131r i\u015f d\u00fcnyas\u0131nda yer almakta ve bunlardan baz\u0131lar\u0131 100 y\u0131l\u0131 a\u015fk\u0131n s\u00fcredir faaliyetlerini s\u00fcrd\u00fcrmektedir. Hem teknik bilgi hem de tedarik zinciri anlay\u0131\u015f\u0131yla, kapsaml\u0131 bir k\u00fcresel pazar anlay\u0131\u015f\u0131na sahibiz ve \u00fcretim i\u015finiz i\u00e7in de\u011ferli bir ortak olaca\u011f\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6b34028b\" data-id=\"6b34028b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cbcfae1 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7cbcfae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"219.81\" height=\"240.58\" viewBox=\"0 0 219.81 240.58\"><path d=\"M109.91,0a31.38,31.38,0,1,0,31.38,31.38A31.47,31.47,0,0,0,109.91,0ZM5.25,10.41A5.23,5.23,0,0,0,0,15.64a5.81,5.81,0,0,0,.05.72V52.3a5.23,5.23,0,0,0,10.46.15V28.32L43.45,61.23A5.23,5.23,0,1,0,51,54l-.15-.15L17.93,20.92h24a5.23,5.23,0,1,0,.15-10.46H5.92A5,5,0,0,0,5.25,10.41Zm209.15,0c-.19,0-.38,0-.58.05H177.9a5.23,5.23,0,1,0-.15,10.46h24.13L169,53.83a5.23,5.23,0,0,0,7.24,7.55l.15-.15,32.92-32.91v24a5.23,5.23,0,0,0,10.46.15V16.35a5.23,5.23,0,0,0-4.47-5.89A5.08,5.08,0,0,0,214.4,10.41Zm-104.49.05A20.92,20.92,0,1,1,89,31.38,20.84,20.84,0,0,1,109.91,10.46ZM86.37,68A28.86,28.86,0,0,0,57.6,96.76V156.9a5.52,5.52,0,0,0,.12,1.14,15.73,15.73,0,0,0,15.57,14.55,15.18,15.18,0,0,0,5.23-1v50.67A18.27,18.27,0,0,0,109.91,235a18.26,18.26,0,0,0,31.38-12.74V171.61a15.18,15.18,0,0,0,5.23,1A15.71,15.71,0,0,0,162.09,158a5.35,5.35,0,0,0,.12-1.13V96.76A28.86,28.86,0,0,0,133.44,68H86.37Zm0,10.46h47.07a18.27,18.27,0,0,1,18.31,18.31V156.9a5.23,5.23,0,1,1-10.46,0V109.83H130.83V222.28a7.85,7.85,0,0,1-15.69,0V162.13H104.68v60.15a7.85,7.85,0,0,1-15.7,0V109.83H78.52V156.9a5.23,5.23,0,1,1-10.46,0V96.76A18.27,18.27,0,0,1,86.37,78.45ZM47,177.77a5.22,5.22,0,0,0-3.59,1.58L10.53,212.27v-24A5.23,5.23,0,0,0,5.38,183H5.22a5.24,5.24,0,0,0-5.15,5.3V224.1a5.22,5.22,0,0,0,4.29,6,5.08,5.08,0,0,0,1.74,0H41.91a5.23,5.23,0,1,0,.15-10.46H17.93l32.91-32.91a5.23,5.23,0,0,0-3.8-9Zm125.58,0a5.23,5.23,0,0,0-3.65,9l32.91,32.91h-24a5.23,5.23,0,1,0-.15,10.46h36a5.23,5.23,0,0,0,6-4.29,5.58,5.58,0,0,0,0-1.73V188.28a5.23,5.23,0,0,0-5.16-5.3h-.15a5.23,5.23,0,0,0-5.15,5.3v24l-32.92-32.92A5.21,5.21,0,0,0,172.62,177.77Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c63bf47 elementor-widget elementor-widget-heading\" data-id=\"7c63bf47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Eri\u015fim Sahas\u0131<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37dfeabf elementor-widget elementor-widget-text-editor\" data-id=\"37dfeabf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>T\u00fcm Avrupa\u2019da ve d\u00fcnya \u00e7ap\u0131nda da ana b\u00f6lgelerde sa\u011flam bir pazar eri\u015fimine sahibiz. Bir PlusChem tedarik\u00e7isi olmak, k\u0131sa s\u00fcrede size f\u0131rsatlar sunar ve size \u00fcr\u00fcnlerinizi halihaz\u0131rda tedarik zinciri kurmu\u015f oldu\u011fumuz yerlere tedarik etme potansiyeli sa\u011flar.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-57b07f98\" data-id=\"57b07f98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a16af3 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"9a16af3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"223.14\" height=\"223.12\" viewBox=\"0 0 223.14 223.12\"><path d=\"M131,0a63,63,0,1,0,63,63A63.25,63.25,0,0,0,131,0Zm-4.85,11.75V58.19H107.27c.61-13.32,3.18-25.51,7.44-34.09C118.13,17.22,122.15,13.71,126.18,11.75Zm9.7,0c4,2,8.05,5.47,11.47,12.35,4.26,8.58,6.83,20.77,7.44,34.09H135.88Zm-26.82,2.76a53,53,0,0,0-3,5.28c-5.1,10.25-7.87,23.76-8.46,38.4H77.94A53.5,53.5,0,0,1,109.06,14.51Zm43.94,0a53.5,53.5,0,0,1,31.12,43.68H164.49C163.9,43.55,161.13,30,156,19.79A53,53,0,0,0,153,14.51ZM77.94,67.89H97.57c.59,14.64,3.36,28.15,8.46,38.4a53,53,0,0,0,3,5.28A53.5,53.5,0,0,1,77.94,67.89Zm29.33,0h18.91v46.44c-4-2-8.05-5.47-11.47-12.36C110.45,93.4,107.88,81.2,107.27,67.89Zm28.61,0h18.91c-.61,13.31-3.18,25.51-7.44,34.08-3.42,6.89-7.44,10.4-11.47,12.36Zm28.61,0h19.63A53.5,53.5,0,0,1,153,111.57a53,53,0,0,0,3-5.28C161.13,96,163.9,82.53,164.49,67.89Zm40,58.17a16.83,16.83,0,0,0-2.64.24,18,18,0,0,0-6.72,2.53L141.3,162c-1.25-.68-2.77-1.43-4.78-2.4-2.3-1.11-4.72-2.25-6.08-2.87C123.12,153.45,99.76,143.82,82,136a60.59,60.59,0,0,0-47.69-.44l-31.26,13a4.85,4.85,0,1,0,3.53,9l.2-.08,31.26-13a50.84,50.84,0,0,1,40.05.37c17.9,7.85,41.64,17.66,48.32,20.68,1.2.54,3.62,1.68,5.87,2.77s4.61,2.29,4.81,2.4a7.12,7.12,0,0,1,3.6,6.23,7.2,7.2,0,0,1-7.28,7.27,7.29,7.29,0,0,1-1.64-.19h0c-.13,0-4-1.1-8.61-2.46l-16.39-4.85c-11.63-3.46-22.87-6.83-22.87-6.83a4.85,4.85,0,1,0-3.18,9.16,2.64,2.64,0,0,0,.4.12s11.25,3.38,22.9,6.84c5.82,1.73,11.74,3.49,16.41,4.86s7.64,2.26,9.09,2.6A16.9,16.9,0,0,0,148.39,169l51.86-32h.05a8.58,8.58,0,0,1,9.45,14.32l-.18.13-76.48,57.95a19.44,19.44,0,0,1-18.25,2.83L58.13,192.19l.23.09A40.53,40.53,0,0,0,19,197.06h0l-16.9,12.4a4.85,4.85,0,0,0,5.74,7.83l16.9-12.4a30.76,30.76,0,0,1,30-3.64l.22.09,56.72,20.11A29.17,29.17,0,0,0,139,217.2l76.49-57.95-.18.12a18.27,18.27,0,0,0-10.73-33.31Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-264d3fab elementor-widget elementor-widget-heading\" data-id=\"264d3fab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Pazar bilgisi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38c37de elementor-widget elementor-widget-text-editor\" data-id=\"38c37de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kimyasal madde tedariki \u00fclkeler aras\u0131ndaki ve hatta yak\u0131n kom\u015fular aras\u0131ndaki bir\u00e7ok k\u00fclt\u00fcrel, ticari ve politik farkl\u0131l\u0131klardan dolay\u0131karma\u015f\u0131k bir i\u015f olabilir. Rakipsiz pazar bilgimiz, b\u00f6lgelerimizi t\u00fcm\u00fcyle tan\u0131d\u0131\u011f\u0131m\u0131z ve faaliyette bulundu\u011fumuz pazarlar\u0131n tamam\u0131n\u0131n dinamiklerini anlamak i\u00e7in bize g\u00fcvenebilece\u011finiz anlam\u0131na geliyor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-31769183 elementor-widget elementor-widget-spacer\" data-id=\"31769183\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1bd682be elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bd682be\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4e00c93\" data-id=\"4e00c93\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd8589a elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"fd8589a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"223.12\" height=\"223.12\" viewBox=\"0 0 223.12 223.12\"><path d=\"M174,0V8.92h33.75L151.72,65,137.08,50.34l-3.21-3.07-3.21,3.07L80.32,100.68,65.68,86,62.47,83,59.27,86l-58,58,6.41,6.41,54.8-54.8L77.12,110.3l3.2,3.07,3.21-3.07L133.87,60,148.51,74.6l3.21,3.07,3.21-3.07,59.26-59.26V49.09h8.93V0Zm13.39,62.47V223.12h8.92V62.47Zm26.77,4.47V223.12h8.93V66.94ZM133.87,89.25V223.12h8.93V89.25Zm26.77,0V223.12h8.93V89.25ZM107.1,107.1v116H116v-116ZM53.55,125v98.17h8.92V125Zm26.77,8.92v89.25h8.93V133.87ZM26.77,151.72v71.4H35.7v-71.4ZM0,169.57v53.55H8.92V169.57Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcb312f elementor-widget elementor-widget-heading\" data-id=\"fcb312f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">K\u00e2rl\u0131<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-647c3ee3 elementor-widget elementor-widget-text-editor\" data-id=\"647c3ee3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Biz h\u0131zl\u0131 b\u00fcy\u00fcyen bir a\u011f\u0131z ve y\u0131lda yakla\u015f\u0131k 1.5 milyar Euro\u2019luk olduk\u00e7a b\u00fcy\u00fck bir devir oran\u0131 iyi durumda oldu\u011fumuzun garantisini sa\u011fl\u0131yor. Sizin a\u00e7\u0131n\u0131zdan, bu durum, halihaz\u0131rda uzun bir s\u00fcredir piyasada var olmam\u0131zla birlikte, gelece\u011fimizin g\u00fcvenli ve sa\u011flam olaca\u011f\u0131 ve uzun vadeli bir tedarik zinciri orta\u011f\u0131 oldu\u011fumuz konusunda emin olabilece\u011finiz anlam\u0131na geliyor.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-50d45485\" data-id=\"50d45485\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77ff4dd9 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"77ff4dd9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"223.94\" height=\"223.98\" viewBox=\"0 0 223.94 223.98\"><path d=\"M58.23,0C35.74,0,21.86,2.22,13.45,4.62a43.52,43.52,0,0,0-9,3.5,15.8,15.8,0,0,0-1.4,1c-.1.07-.31.07-.42.14a4.12,4.12,0,0,0-1.26,1H1.27l-.14.28a2.78,2.78,0,0,0-.42.42l-.7.56V12.6a5.23,5.23,0,0,0,0,.56V219.44a4.54,4.54,0,0,0,2.22,3.94A4.48,4.48,0,0,0,9,219.44V137.29a71.36,71.36,0,0,1,9.8-3.08c8.53-2.15,21.62-4.33,39.46-4.33,17.48,0,30.44,4.3,46.19,8.81s34.08,9.1,61.3,9.1c31.45,0,56-14,56-14l2.24-1.26V10.36L217.36,14a114.65,114.65,0,0,1-51.64,12.87c-21.4,0-36.32-6.3-52.07-13S81.34,0,58.23,0Zm0,9c21.29,0,36.18,6.29,51.93,13s32.38,13.86,55.56,13.86A110.83,110.83,0,0,0,215,24.63V126.94a108.41,108.41,0,0,1-49.26,11.89c-26.21,0-43.39-4.37-58.92-8.81s-29.62-9.1-48.57-9.1c-18.58,0-32.33,2.29-41.56,4.62A37.47,37.47,0,0,0,9,128.2V15.81a38.78,38.78,0,0,1,7-2.51C23.32,11.21,36.33,9,58.23,9Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-465020a5 elementor-widget elementor-widget-heading\" data-id=\"465020a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ba\u011f\u0131ms\u0131z<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7579b60e elementor-widget elementor-widget-text-editor\" data-id=\"7579b60e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>PlusChem\u2018de kendi kaderimizi kontrol etti\u011fimizi s\u00f6ylemekten gururluyuz. Ve bir aile \u015firketi olarak, bizimle \u00e7al\u0131\u015ft\u0131\u011f\u0131n\u0131zda, b\u00fct\u00fcn kararlar\u0131 m\u00fc\u015fterilerimizin, ortaklar\u0131m\u0131z\u0131n ve tedarik zincirinin \u00fcst\u00fcn yarar\u0131 \u00e7er\u00e7evesinde verece\u011fimizden emin olabilirsiniz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-71f8b8e1\" data-id=\"71f8b8e1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d4a1662 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"5d4a1662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"215.06\" height=\"215.06\" viewBox=\"0 0 215.06 215.06\"><path d=\"M113,0C102.05,0,93.74,3.79,89.44,10.55c-3.87,6.08-3.93,13.74-2.14,21.6A9.28,9.28,0,0,0,86.08,38a13.57,13.57,0,0,0,2.24,6.65c.47.65,1.3.68,1.93,1.15.65,2.55,1.32,5.18,2.59,6.88a24.47,24.47,0,0,0,2.63,3l.11.08V60.5a5,5,0,0,1-2.51,2.34c-1.84,1-4.59,2.1-7.57,3.55a26.91,26.91,0,0,0-9,6.5,21.38,21.38,0,0,0-4.85,12.87,4.79,4.79,0,0,0,4.52,5h67.16A4.78,4.78,0,0,0,148.15,86a2.26,2.26,0,0,0,0-.26,21.44,21.44,0,0,0-4.84-12.87,26.91,26.91,0,0,0-9-6.5c-3-1.45-5.74-2.52-7.57-3.56a5.08,5.08,0,0,1-2.52-2.33V55.71c0-.05.11-.08.15-.12A26.31,26.31,0,0,0,127,52.54c1.22-1.69,1.87-4.23,2.51-6.69.63-.47,1.46-.51,1.93-1.16a13.53,13.53,0,0,0,2.25-6.64,10.51,10.51,0,0,0-.59-5.11c-.09-.21-.46-.33-.57-.54,1.34-5.47,1.77-11.31-.34-16.66-2-5.11-7.23-8.62-13.75-9.89l-1-2.7A4.78,4.78,0,0,0,113,0Zm-3.15,10.09.4,1.1a4.77,4.77,0,0,0,4.49,3.15c5.7,0,7.35,1.78,8.58,4.91s1.1,8.21-.31,12.79a4.76,4.76,0,0,0,1.22,4.82.37.37,0,0,1,0,.14,4.11,4.11,0,0,1-.41,1.74A4.78,4.78,0,0,0,121,43.07a9.35,9.35,0,0,1-1.74,3.87,17.21,17.21,0,0,1-1.62,1.92c-.48.48-1.09.84-.53.52a4.78,4.78,0,0,0-2.4,4.14v8.29a4.8,4.8,0,0,0,.26,1.55c1.31,3.83,4.31,6.22,7.09,7.79s5.62,2.63,8.09,3.83A18,18,0,0,1,136,79.11c.42.48.44,1.56.77,2.13H83c.33-.57.35-1.65.76-2.13A17.83,17.83,0,0,1,89.69,75c2.47-1.2,5.31-2.26,8.09-3.84s5.79-4,7.1-7.79a4.8,4.8,0,0,0,.26-1.55V53.52a4.77,4.77,0,0,0-2.43-4.15c.48.27-.1-.08-.58-.54A16.1,16.1,0,0,1,100.52,47a8.66,8.66,0,0,1-1.76-4A4.77,4.77,0,0,0,96,38.66a3.91,3.91,0,0,1-.42-1.73c0-.19,0-.13.05-.19a4.78,4.78,0,0,0,1.19-4.68c-2-7.14-1.57-12.81.69-16.38C99.42,12.67,103.45,10.73,109.81,10.09ZM71.48,33.44a4.62,4.62,0,0,0-1.71.42C40,46.87,19.11,75,19.11,107.71c0,2.51.13,5,.37,7.46a4.78,4.78,0,0,0,9.53-.75c0-.06,0-.12,0-.19q-.31-3.23-.32-6.52c0-28.64,18.23-53.44,44.93-65.1a4.78,4.78,0,0,0-2.12-9.17Zm75.83,1.9a4.78,4.78,0,0,0-2,9.08c24.58,12.31,41,36.06,41,63.29,0,2.2-.1,4.38-.31,6.52a4.78,4.78,0,0,0,9.49,1.13c0-.07,0-.13,0-.19q.36-3.69.36-7.46c0-31.09-18.85-58.08-46.32-71.84A4.78,4.78,0,0,0,147.31,35.34Zm-106,88.92c-10.9,0-19.22,3.79-23.52,10.54-3.87,6.09-3.93,13.75-2.14,21.6a9.32,9.32,0,0,0-1.22,5.83,13.49,13.49,0,0,0,2.24,6.64c.47.65,1.31.69,1.93,1.16.65,2.54,1.32,5.17,2.59,6.88a25.34,25.34,0,0,0,2.63,3l.11.08v4.74a5,5,0,0,1-2.51,2.33c-1.84,1-4.58,2.11-7.57,3.56a26.91,26.91,0,0,0-9,6.5A21.32,21.32,0,0,0,0,210a4.76,4.76,0,0,0,4.51,5H71.68a4.78,4.78,0,0,0,4.78-4.78,2.26,2.26,0,0,0,0-.26,21.32,21.32,0,0,0-4.84-12.87,26.91,26.91,0,0,0-9-6.5c-3-1.45-5.73-2.52-7.57-3.56-1.67-1-2.19-1.61-2.51-2.33V180l.15-.12a25.32,25.32,0,0,0,2.58-3c1.23-1.69,1.87-4.23,2.51-6.69.63-.48,1.47-.51,1.94-1.16A13.54,13.54,0,0,0,62,162.3a10.47,10.47,0,0,0-.6-5.1c-.09-.21-.46-.33-.56-.54,1.33-5.48,1.77-11.31-.35-16.67-2-5.11-7.23-8.61-13.75-9.88l-1-2.71A4.76,4.76,0,0,0,41.27,124.26Zm138.6,0c-10.91,0-19.23,3.79-23.52,10.54-3.88,6.09-3.94,13.75-2.14,21.6a9.25,9.25,0,0,0-1.22,5.83,13.49,13.49,0,0,0,2.24,6.64c.46.65,1.3.69,1.93,1.16.64,2.54,1.32,5.17,2.58,6.88a25.35,25.35,0,0,0,2.64,3l.11.08v4.74a5,5,0,0,1-2.51,2.33c-1.84,1-4.59,2.11-7.57,3.56a26.71,26.71,0,0,0-9,6.5A21.38,21.38,0,0,0,138.6,210a4.78,4.78,0,0,0,4.51,5h67.17a4.78,4.78,0,0,0,4.78-4.78c0-.09,0-.17,0-.26a21.38,21.38,0,0,0-4.85-12.87,26.71,26.71,0,0,0-9-6.5c-3-1.45-5.73-2.52-7.57-3.56-1.66-1-2.19-1.61-2.51-2.33V180l.15-.12a25.33,25.33,0,0,0,2.59-3c1.22-1.69,1.87-4.23,2.51-6.69.63-.48,1.46-.51,1.93-1.16a13.54,13.54,0,0,0,2.25-6.65,10.47,10.47,0,0,0-.6-5.1c-.08-.21-.45-.33-.56-.54,1.34-5.48,1.77-11.31-.34-16.67-2-5.11-7.24-8.61-13.75-9.88l-1-2.71A4.77,4.77,0,0,0,179.87,124.26ZM38.12,134.35l.4,1.1A4.77,4.77,0,0,0,43,138.59c5.7,0,7.35,1.79,8.59,4.91s1.1,8.22-.32,12.8a4.81,4.81,0,0,0,1.22,4.82.37.37,0,0,1,0,.14,3.78,3.78,0,0,1-.41,1.73,4.79,4.79,0,0,0-2.78,4.33,9.4,9.4,0,0,1-1.73,3.88,17.15,17.15,0,0,1-1.63,1.91c-.48.48-1.08.85-.52.52A4.78,4.78,0,0,0,43,177.78v8.29a4.8,4.8,0,0,0,.26,1.55c1.31,3.82,4.31,6.22,7.1,7.79S56,198,58.46,199.24a18,18,0,0,1,5.89,4.12c.41.49.43,1.56.76,2.14H11.35c.33-.58.35-1.65.76-2.14A18,18,0,0,1,18,199.25c2.47-1.21,5.31-2.26,8.1-3.84s5.78-4,7.09-7.79a4.8,4.8,0,0,0,.26-1.55v-8.29A4.76,4.76,0,0,0,31,173.63c.49.27-.09-.08-.57-.55a15.13,15.13,0,0,1-1.62-1.85,8.62,8.62,0,0,1-1.75-4,4.79,4.79,0,0,0-2.78-4.33,4.18,4.18,0,0,1-.42-1.74c0-.18,0-.12.05-.18a4.81,4.81,0,0,0,1.2-4.68c-2.05-7.14-1.58-12.82.69-16.38C27.73,136.92,31.76,135,38.12,134.35Zm138.59,0,.4,1.1a4.78,4.78,0,0,0,4.49,3.14c5.71,0,7.36,1.79,8.59,4.91s1.1,8.22-.32,12.8a4.79,4.79,0,0,0,1.23,4.82,1,1,0,0,1,0,.14,4.14,4.14,0,0,1-.41,1.73,4.78,4.78,0,0,0-2.78,4.33,9.46,9.46,0,0,1-1.74,3.88,17.17,17.17,0,0,1-1.62,1.91c-.48.48-1.09.85-.53.52a4.81,4.81,0,0,0-2.41,4.15v8.29a4.81,4.81,0,0,0,.27,1.55,14.63,14.63,0,0,0,7.09,7.79c2.78,1.58,5.62,2.62,8.09,3.83a18,18,0,0,1,5.89,4.12c.42.49.44,1.56.77,2.14H149.94c.33-.58.35-1.65.77-2.14a18,18,0,0,1,5.89-4.11c2.47-1.21,5.31-2.26,8.09-3.84s5.79-4,7.09-7.79a4.81,4.81,0,0,0,.27-1.55v-8.29a4.78,4.78,0,0,0-2.43-4.15c.48.27-.1-.08-.58-.55a15.13,15.13,0,0,1-1.61-1.85,8.66,8.66,0,0,1-1.76-4,4.77,4.77,0,0,0-2.77-4.33,4,4,0,0,1-.42-1.74c0-.18,0-.12.05-.18a4.78,4.78,0,0,0,1.19-4.68c-2.05-7.14-1.58-12.82.69-16.38C166.33,136.92,170.36,135,176.71,134.35Zm-33.35,39.59a4.89,4.89,0,0,0-1.94.5,83.68,83.68,0,0,1-67.78,0,4.78,4.78,0,1,0-3.91,8.72,93.28,93.28,0,0,0,75.59,0,4.78,4.78,0,0,0-2-9.22Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74d3c073 elementor-widget elementor-widget-heading\" data-id=\"74d3c073\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0130\u015f birli\u011fi<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e0df41c elementor-widget elementor-widget-text-editor\" data-id=\"2e0df41c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0130\u015f birli\u011fi yapman\u0131n g\u00fcc\u00fcne inan\u0131yoruz ve kimyasal madde da\u011f\u0131t\u0131m a\u011f\u0131m\u0131z\u0131 y\u00f6netecek uzman \u00fcreticilerle \u00e7al\u0131\u015fmaktan keyif al\u0131yoruz. Bir \u00fcretici olarak sizin uzmanl\u0131\u011f\u0131n\u0131z bizim pazar bilgimizle birle\u015fti\u011finde, ger\u00e7ek bir i\u015fbirlik\u00e7i yakla\u015f\u0131m\u0131n kar\u015f\u0131l\u0131\u011f\u0131n\u0131 alacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><div class=\"switcher-section-2\" style=\"display:none;\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"19584\" class=\"elementor elementor-19584 elementor-4337\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3aea2335 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3aea2335\" data-element_type=\"section\" data-e-type=\"section\" id=\"partners-section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-97748c4\" data-id=\"97748c4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-478f0fc3 elementor-widget elementor-widget-heading\" data-id=\"478f0fc3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Potansiyel ortaklar i\u00e7in<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-59f16abb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59f16abb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2143863e\" data-id=\"2143863e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7873aeb5 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"7873aeb5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"220.42\" height=\"215.14\" viewBox=\"0 0 220.42 215.14\"><path d=\"M110.32,0a10,10,0,1,0,10,10A10,10,0,0,0,110.32,0Zm-30,10a10,10,0,1,0,10,10A10,10,0,0,0,80.32,10Zm60,0a10,10,0,1,0,10,10A10,10,0,0,0,140.33,10ZM5.07,20a5,5,0,1,0-.14,10h.14c25.47,0,40.64,7.15,50.37,18.05s14.2,26.24,16,43.26l.1,1.06L89.81,123.8a1.72,1.72,0,0,1-.7,2.64l-17.24,8.62L67,168.92a24.19,24.19,0,0,1-5.64,11.3c-2.9,3.23-6.23,4.94-8.9,4.83H29.85v25a5,5,0,1,0,10,.15V195.05H52c6.77.27,12.53-3.47,16.73-8.15a32.75,32.75,0,0,0,8.09-16.4v0L81,141.67l12.86-6.43.09-.06a12,12,0,0,0,4.58-16.24l0,0-17.41-30c-2-17.59-6.75-34.62-18.23-47.48C51.1,28.19,32.47,20,5.07,20Zm210.28,0c-27.4,0-46,8.18-57.83,21.39C146,54.27,141.35,71.3,139.31,88.9l-17.43,30,0,0a12.06,12.06,0,0,0,4.58,16.24l.1.05,12.86,6.44,4.17,28.78v0a32.83,32.83,0,0,0,8.07,16.41c4.21,4.68,10,8.41,16.74,8.14h12.18v15a5,5,0,1,0,10,.15V185.06H168c-2.67.11-6-1.61-8.89-4.84a24.26,24.26,0,0,1-5.65-11.3l-4.89-33.86-17.25-8.62a1.72,1.72,0,0,1-.71-2.64l18.24-31.41.12-1.06c1.83-17,6.3-32.37,16-43.27s24.9-18,50.36-18a5,5,0,0,0,.14-10A.33.33,0,0,0,215.35,20ZM10.3,55a10,10,0,1,0,10,10A10,10,0,0,0,10.3,55Zm30,0a10,10,0,1,0,10,10A10,10,0,0,0,40.31,55Zm140,0a10,10,0,1,0,10,10A10,10,0,0,0,180.34,55ZM10.3,85a10,10,0,1,0,10,10A10,10,0,0,0,10.3,85Zm30,0a10,10,0,1,0,10,10A10,10,0,0,0,40.31,85Zm140,0a10,10,0,1,0,10,10A10,10,0,0,0,180.34,85Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-628de1ab elementor-widget elementor-widget-heading\" data-id=\"628de1ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Payla\u015f\u0131m<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4364f317 elementor-widget elementor-widget-text-editor\" data-id=\"4364f317\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bol miktarda bilgiye sahibiz ve \u00fcr\u00fcnler veya a\u011f genelindeki belirli pazarlara ili\u015fkinpazar bilgisi payla\u015f\u0131m\u0131ndan geni\u015f \u00f6l\u00e7\u00fcde faydalanacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4661816c\" data-id=\"4661816c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fae338 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"fae338\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"217.47\" height=\"203.28\" viewBox=\"0 0 217.47 203.28\"><path d=\"M61.54,0A61.54,61.54,0,0,0,18.08,105l14.49,14.49a14.52,14.52,0,0,0-.32,3,13.59,13.59,0,0,0,4.25,9.91L43.11,139a12.76,12.76,0,0,0,9.57,4.21,14.15,14.15,0,0,0,4.14,9l6.63,6.61a13.58,13.58,0,0,0,9,4.17,13.58,13.58,0,0,0,4.21,9.54l6.61,6.63a12.8,12.8,0,0,0,9.56,4.2,13.51,13.51,0,0,0,4.15,9l6.63,6.61a13.52,13.52,0,0,0,9.91,4.26,14.35,14.35,0,0,0,9.91-4.26l14.17-14.18a13,13,0,0,0,4.12-8.19,13.66,13.66,0,0,0,8.18-4.08l8.51-8.51a14.16,14.16,0,0,0,4.13-9,12.87,12.87,0,0,0,9.58-4.21l6.61-6.63a13.17,13.17,0,0,0,4.19-9.06,13.21,13.21,0,0,0,9.5-4.65L199,123.9c5.28-4.84,5.59-12.9,1.05-18.59a61.4,61.4,0,0,0,17.39-42.83c0-16.54-6.15-32.6-18-43.95a62.32,62.32,0,0,0-87.41-.46l-3.55,3.54L105,18.07A61.28,61.28,0,0,0,61.54,0Zm0,9.56A53.43,53.43,0,0,1,98.4,24.68l3.31,3.3L77.62,52.08a21.67,21.67,0,0,0,0,30.72A22.24,22.24,0,0,0,93.2,89.42a20.72,20.72,0,0,0,15.13-6.16L136.64,55l55.3,56.2a4.56,4.56,0,0,1,0,6.62l-6.61,6.61a4.57,4.57,0,0,1-6.6,0L149.9,96a4.67,4.67,0,0,0-6.61,6.61L172.12,131a4.58,4.58,0,0,1,0,6.61l-6.63,6.62a4.59,4.59,0,0,1-6.62,0l-28.35-28.35a4.85,4.85,0,0,0-7.09,6.63l28.35,28.35a4.22,4.22,0,0,1,1.44,3.28,4.27,4.27,0,0,1-1.44,3.32l-8.49,8.49a4.55,4.55,0,0,1-3.8,1.33A14.74,14.74,0,0,0,137.6,165L131,158.4a13.91,13.91,0,0,0-9.53-3.86,14.29,14.29,0,0,0-4.17-9.38l-6.61-6.61a13.08,13.08,0,0,0-9-4.17,13.49,13.49,0,0,0-4.23-9.52l-6.61-6.63a13.88,13.88,0,0,0-9.52-3.85A14.29,14.29,0,0,0,77.14,105l-6.61-6.61c-5.2-5.66-14.19-5.66-19.86,0l-13,13-13-13a52.18,52.18,0,0,1,0-73.71A53.42,53.42,0,0,1,61.54,9.56Zm94,.48a53.42,53.42,0,0,1,36.84,15.12l.48.46A51,51,0,0,1,208,62.48,51.85,51.85,0,0,1,193.57,98.6L140.45,45.46a1.52,1.52,0,0,1-.28-.19c-.09-.09-.11-.2-.2-.27a4.56,4.56,0,0,0-6.61,0L101.71,76.65a12.54,12.54,0,0,1-17.48,0,12.51,12.51,0,0,1,0-17.94L111.4,31.54l.22.22,7.08-6.6A52.68,52.68,0,0,1,155.58,10Zm-94.5,93.08a5.06,5.06,0,0,1,3.29,1.4L71,111.15a4.57,4.57,0,0,1,0,6.62L56.82,132a4.6,4.6,0,0,1-6.63,0l-6.6-6.63a4.24,4.24,0,0,1-1.41-3.3,4.31,4.31,0,0,1,1.41-3.32l14.17-14.18A4.31,4.31,0,0,1,61.08,103.12Zm19.83,20.3a4.27,4.27,0,0,1,3.32,1.44l6.6,6.61a4.53,4.53,0,0,1,0,6.61L76.66,152.25a4.58,4.58,0,0,1-6.61,0l-6.6-6.61a4.53,4.53,0,0,1,0-6.61l14.17-14.17A4.23,4.23,0,0,1,80.91,123.42Zm20,19.86a3.81,3.81,0,0,1,3.12,1.4l6.62,6.63a4.57,4.57,0,0,1,0,6.62L96.52,172.11a4.6,4.6,0,0,1-6.63,0l-6.62-6.63a4.27,4.27,0,0,1-1.41-3.3,4.35,4.35,0,0,1,1.41-3.32l14.17-14.18A5,5,0,0,1,101,143.28Zm20.12,20.3a4.27,4.27,0,0,1,3.32,1.44l6.61,6.61a4.56,4.56,0,0,1,0,6.61l-14.18,14.17a4.58,4.58,0,0,1-6.61,0l-6.6-6.61a4.27,4.27,0,0,1-1.44-3.32,4.22,4.22,0,0,1,1.44-3.28L117.78,165A4.23,4.23,0,0,1,121.07,163.58Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-247172d6 elementor-widget elementor-widget-heading\" data-id=\"247172d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ortak \u00e7al\u0131\u015fma<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c08cefe elementor-widget elementor-widget-text-editor\" data-id=\"c08cefe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Uluslararas\u0131 grup sinerjisinde al\u0131\u015f\u0131 ve sat\u0131\u015f\u0131 veya i\u015f birli\u011fini en \u00fcst d\u00fczeye \u00e7\u0131karmak s\u00f6z konusu oldu\u011funda, bir PlusChem orta\u011f\u0131 olarak olduk\u00e7a fayda sa\u011flayacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-b24f3c2\" data-id=\"b24f3c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33a2c3fb elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"33a2c3fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"203.54\" height=\"226.8\" viewBox=\"0 0 203.54 226.8\"><path d=\"M87.89,0A55.57,55.57,0,0,0,32.38,55.51V78.64H13.88A13.9,13.9,0,0,0,0,92.52v111a13.89,13.89,0,0,0,13.88,13.87H116a55.29,55.29,0,0,1-6.74-9.25H13.88a4.63,4.63,0,0,1-4.63-4.62v-111a4.63,4.63,0,0,1,4.63-4.63h148a4.63,4.63,0,0,1,4.63,4.63v33.21a55.79,55.79,0,0,1,9.25,2.39V92.52A13.89,13.89,0,0,0,161.9,78.64H143.4V55.51A55.57,55.57,0,0,0,87.89,0Zm0,9.25a46.31,46.31,0,0,1,46.26,46.26V78.64H41.63V55.51A46.31,46.31,0,0,1,87.89,9.25Zm0,115.65A13.63,13.63,0,0,0,74,138.78,13.23,13.23,0,0,0,78.64,149v13a9.25,9.25,0,1,0,18.5,0V149a13.23,13.23,0,0,0,4.63-10.17A13.63,13.63,0,0,0,87.89,124.9Zm69.39,9.38a46.26,46.26,0,1,0,46.26,46.26A46.4,46.4,0,0,0,157.28,134.28Zm0,9.26a37,37,0,1,1-37,37A37.12,37.12,0,0,1,157.28,143.54Zm19.89,15.73-25,29.13-15.27-11.56-5.54,7.4,21.73,16.66,31-35.63Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-172a1792 elementor-widget elementor-widget-heading\" data-id=\"172a1792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Eri\u015fim sa\u011flama<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29559048 elementor-widget elementor-widget-text-editor\" data-id=\"29559048\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>A\u011f\u0131m\u0131z\u0131n bir \u00fcyesi olarak, PlusChem\u2018e ba\u011fl\u0131 deniza\u015f\u0131r\u0131 ofislere kaynak bulma, tedarik ve lojistik deste\u011fi i\u00e7in do\u011frudan eri\u015fim imkan\u0131na sahip olacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac57c5f elementor-widget elementor-widget-spacer\" data-id=\"2ac57c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b09edab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b09edab\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7f9720ab\" data-id=\"7f9720ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1de842b4 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"1de842b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"217.98\" height=\"206.24\" viewBox=\"0 0 217.98 206.24\"><path d=\"M78.19,0A35.6,35.6,0,0,0,42.65,35.54a35.16,35.16,0,0,0,3.55,15.4l8.44-4.15a25.61,25.61,0,0,1-2.51-11.25,26.06,26.06,0,0,1,52.12,0h9.48A35.61,35.61,0,0,0,78.19,0Zm88.55,20.73a5.66,5.66,0,0,0-.59.15,2,2,0,0,0-.29.15c-12,3-25.77,10.22-34.51,26.51a122.26,122.26,0,0,0-25.91-3.11c-26.95,0-47.85,8.38-64.27,21.17A59.68,59.68,0,0,0,22.06,92.11a23.79,23.79,0,0,1-5.62-2.81c-3.72-2.54-7-6-7-12.44,0-5.11,2.39-9.39,6.37-11.11a4.74,4.74,0,0,0-1.93-9.18,5,5,0,0,0-1.78.44C4.28,60.4,0,68.56,0,76.86A24.4,24.4,0,0,0,11.11,97.14a30.77,30.77,0,0,0,8.14,4,86.79,86.79,0,0,0-1.92,23.1c.88,21.11,15.17,36.58,25.91,45.17h.15a5.29,5.29,0,0,1,1.33,1.33c.08.13.3-.16-.15,1.19-1.42,4.37-4.14,11-4.14,11V183a12.89,12.89,0,0,0,7.4,16.59v.15l15.25,5.62A13,13,0,0,0,79.82,198s1.89-5.33,3.55-9.77a3.44,3.44,0,0,1,.59-1c.19,0,.21.07.6.15a89.15,89.15,0,0,0,20.88,2.52,186.88,186.88,0,0,0,21-1.34c.6,0,.84,0,1,0a4.67,4.67,0,0,1,.15.45c0,.07,0,.07,0,.14,1.52,4.54,3.35,8.76,3.41,8.89s.11.07.14.15a12.83,12.83,0,0,0,16.44,7.25l15.25-5.62v-.15A12.86,12.86,0,0,0,170.3,183l-2.37-6.36a5.62,5.62,0,0,0-.45-.74s.15,0,.15,0-.65.24.89-.6a61.06,61.06,0,0,0,25.92-27.54,8.27,8.27,0,0,1,1.33-2.22c.37-.35.59-.59,2.07-.59h7.7A12.52,12.52,0,0,0,218,132.54V109.43A12.5,12.5,0,0,0,205.54,97h-7.7a4.55,4.55,0,0,1-1.63-.15,52.73,52.73,0,0,0-31.84-39.39c.25-9.76,2.39-17.48,7.11-30.21a4.74,4.74,0,0,0-4.74-6.52Zm-7.4,13.33C156.47,43,154.43,51,154.6,60.27a4.72,4.72,0,0,0,3.26,4.44c19.82,6.93,27.14,22.35,29,34.21.73,4.52,5.54,7.55,11,7.55h7.7a2.91,2.91,0,0,1,3,3v23.11a2.91,2.91,0,0,1-3,3h-7.7a12.85,12.85,0,0,0-8.59,3.11,14.76,14.76,0,0,0-3.4,5,50.88,50.88,0,0,1-21.77,23.25,11.14,11.14,0,0,0-5.93,8.74,7.53,7.53,0,0,0,1,4.29H159l.3.74,2.07,5.78a3.37,3.37,0,0,1-1.92,4.44l-15.26,5.78a3.45,3.45,0,0,1-4.44-2.08v-.14s-1.85-4.24-3.26-8.45a10.14,10.14,0,0,0-4-5.77c-2.3-1.43-4.56-1.31-6.67-1.19-4.22.28-9.66,1.34-20.43,1.34-10.17,0-15.18-1.63-19.25-2.37-2-.37-4.54-.71-7.11.74s-3.54,3.79-4.45,6.22c-1.62,4.37-3.7,9.62-3.7,9.62a3.46,3.46,0,0,1-4.44,2.08l-15.25-5.78a3.39,3.39,0,0,1-1.93-4.44c.08-.2,2.67-6.55,4.3-11.55a11.18,11.18,0,0,0-.74-9A13.14,13.14,0,0,0,49.16,162c-9.58-7.67-21.65-21.29-22.36-38.21C25.8,99.79,34,83.06,46.94,73c15-11.65,33.47-19.11,58.5-19.11a113.35,113.35,0,0,1,27.1,3.26A4.75,4.75,0,0,0,138,54.5C143.33,42.78,151.19,37.6,159.34,34.06Zm4,63.23a9,9,0,0,0-9,9,9,9,0,1,0,18.07,0A9,9,0,0,0,163.34,97.29Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1eb66e elementor-widget elementor-widget-heading\" data-id=\"e1eb66e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Tasarruf<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a918d84 elementor-widget elementor-widget-text-editor\" data-id=\"a918d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Deniza\u015f\u0131r\u0131 sanayi fuarlar\u0131na eri\u015fim ve Avrupa i\u00e7inde ve d\u0131\u015f\u0131nda tedarik\u00e7i ziyaretleri gibi ihtiya\u00e7lar s\u00f6z konusu oldu\u011funda , maliyetlerden \u00f6nemli miktarda tasarruf sa\u011flayacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-45283d53\" data-id=\"45283d53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-35de3664 elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"35de3664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"215.06\" height=\"215.06\" viewBox=\"0 0 215.06 215.06\"><path d=\"M107.53,0a107.68,107.68,0,1,0,90.26,49.19l-4.17,4.17L191,56a98.73,98.73,0,1,1-22.64-25.38v9.49L156.92,51.53a74,74,0,1,0,12.46,14l-6.78,6.77a65.93,65.93,0,1,1-12.29-14.15L133.73,74.72a42.13,42.13,0,1,0,11.73,14.72l-7.13,7.12a32.89,32.89,0,1,1-11.24-15.2L109.94,98.51a9,9,0,0,0-2.41-.33,9.36,9.36,0,1,0,9,6.93l58.36-58.36H187l23.37-23.37h-18.7V4.68l-18.1,18.1A107,107,0,0,0,107.53,0Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-840be6f elementor-widget elementor-widget-heading\" data-id=\"840be6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">K\u00e2r<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7359749e elementor-widget elementor-widget-text-editor\" data-id=\"7359749e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>D\u00fczenli olarak a\u011f ortaklar\u0131m\u0131z i\u00e7in maliyet tasarrufu sa\u011flayan grup \u00e7ap\u0131ndaki ortak pazar giri\u015fimlerimizi i\u015fletiyoruz ve \u015firketinizin yurt i\u00e7inde ve yurt d\u0131\u015f\u0131nda tan\u0131t\u0131m\u0131na yard\u0131m ediyoruz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-10dd135d\" data-id=\"10dd135d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1564629e elementor-view-stacked elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"1564629e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"219.97\" height=\"219.96\" viewBox=\"0 0 219.97 219.96\"><path d=\"M110,0a27.5,27.5,0,1,0,27.49,27.5A27.56,27.56,0,0,0,110,0Zm0,9.17A18.33,18.33,0,1,1,91.66,27.5,18.26,18.26,0,0,1,110,9.17Zm.12,50.4c-20.17,0-31.95,5.36-38.5,12.05a25.19,25.19,0,0,0-7.45,17.29v44.9A12.89,12.89,0,0,0,77,146.64h5.51v51.93A12.29,12.29,0,0,0,94.72,210.8h30.54a12.3,12.3,0,0,0,12.22-12.23V146.64H143a12.9,12.9,0,0,0,12.83-12.83V88.91a25.21,25.21,0,0,0-7.32-17.27C142,64.93,130.29,59.57,110.11,59.57Zm0,9.17c18.58,0,27.41,4.74,31.8,9.27a16.05,16.05,0,0,1,4.74,10.9v44.9a3.65,3.65,0,0,1-3.67,3.67h-5.5V100.82a4.59,4.59,0,0,0-4.65-4.66,4.6,4.6,0,0,0-4.51,4.66v97.75a3,3,0,0,1-3.06,3.06H94.72a3,3,0,0,1-3.06-3.06V100.82A4.59,4.59,0,0,0,87,96.16a4.6,4.6,0,0,0-4.51,4.66v36.66H77a3.64,3.64,0,0,1-3.65-3.67V88.91A16.15,16.15,0,0,1,78.16,78C82.6,73.48,91.51,68.74,110.11,68.74ZM56.63,141C27.25,156.33,8.72,183.41.22,209.37a4.6,4.6,0,0,0,2.94,5.78,4.5,4.5,0,0,0,1.43.23A4.61,4.61,0,0,0,9,212.23a116.27,116.27,0,0,1,13.85-28.44,93.42,93.42,0,0,1,5.55-7.56,102.46,102.46,0,0,1,33.1-27.35A21.57,21.57,0,0,1,56.63,141Zm107.38.35a21.61,21.61,0,0,1-5,7.81,102.49,102.49,0,0,1,32.64,27.08c1.43,1.54,4.18,5.64,5.53,7.56A115.64,115.64,0,0,1,211,212.23a4.59,4.59,0,0,0,4.37,3.15,4.58,4.58,0,0,0,4.35-6C211.31,183.61,193,156.76,164,141.34Zm-17.63,19a4.72,4.72,0,0,0-1.74.45,4.6,4.6,0,1,0,1.74-.45Zm-73,.48A4.58,4.58,0,0,0,69,163.42,4.65,4.65,0,0,0,71,169.56a4.74,4.74,0,0,0,2,.44,4.48,4.48,0,0,0,4.09-2.5,4.55,4.55,0,0,0-2-6.14A4.61,4.61,0,0,0,73.4,160.87Zm79.21,11.69a4.59,4.59,0,0,0,.47,9.15,4.33,4.33,0,0,0,2.18-.55,4.59,4.59,0,0,0-2.65-8.6ZM67.1,173a4.59,4.59,0,0,0-2.62,8.59,4.4,4.4,0,0,0,2.15.56,4.64,4.64,0,0,0,4.05-2.38A4.61,4.61,0,0,0,67.1,173Zm-31.87,4.85A4.56,4.56,0,0,0,32,185.65,4.74,4.74,0,0,0,35.23,187a4.53,4.53,0,0,0,4.59-4.58,4.66,4.66,0,0,0-1.36-3.26A4.58,4.58,0,0,0,35.23,177.86Zm149.51,0a4.71,4.71,0,0,0-3.27,1.27,4.71,4.71,0,0,0,0,6.52,4.67,4.67,0,0,0,6.51,0,4.64,4.64,0,0,0,0-6.52A4.69,4.69,0,0,0,184.74,177.86ZM47.08,182.21a4.56,4.56,0,0,0-.69,8.93,3.5,3.5,0,0,0,1.23.18A4.5,4.5,0,0,0,52,188a4.58,4.58,0,0,0-3.1-5.69A4.23,4.23,0,0,0,47.08,182.21Zm125.79,0a4.11,4.11,0,0,0-1.8.13,4.61,4.61,0,0,0,1.23,9,4.84,4.84,0,0,0,1.29-.2,4.63,4.63,0,0,0,3.17-5.67A4.68,4.68,0,0,0,172.87,182.21ZM59.54,185.4a4.59,4.59,0,0,0-.1,9,7.75,7.75,0,0,0,1,.07,4.56,4.56,0,0,0,1-9v0A4.7,4.7,0,0,0,59.54,185.4Zm99.07,0a4.57,4.57,0,0,0,1,9.05,7.77,7.77,0,0,0,1-.07,4.65,4.65,0,0,0,3.53-5.46,4.59,4.59,0,0,0-5.46-3.49Zm-85.28,2.47a4.57,4.57,0,0,0-3.26,1.29,4.77,4.77,0,0,0-1.33,3.24,4.62,4.62,0,0,0,1.33,3.2,4.58,4.58,0,0,0,7.84-3.2,4.76,4.76,0,0,0-1.32-3.24A4.59,4.59,0,0,0,73.33,187.89Zm73.32,0a4.57,4.57,0,0,0-3.26,1.29,4.67,4.67,0,0,0-1.32,3.24,4.58,4.58,0,0,0,9.16,0,4.76,4.76,0,0,0-1.32-3.24A4.57,4.57,0,0,0,146.65,187.89Zm18.54,9.36a4.4,4.4,0,0,0-1.77.3,4.62,4.62,0,0,0-2.58,6,4.53,4.53,0,0,0,4.28,2.89,4.32,4.32,0,0,0,1.7-.33,4.58,4.58,0,0,0,2.56-5.94A4.63,4.63,0,0,0,165.19,197.25Zm-110.62.5a4.56,4.56,0,0,0-4.16,2.92v0A4.59,4.59,0,0,0,53,206.57a4.19,4.19,0,0,0,1.68.35,4.6,4.6,0,0,0,1.71-8.87A5,5,0,0,0,54.57,197.75Zm115.51,12.58a4.48,4.48,0,0,0-1.81.11A4.56,4.56,0,0,0,165,216a4.63,4.63,0,0,0,4.44,3.43,5.32,5.32,0,0,0,1.2-.14,4.6,4.6,0,0,0-.54-9Zm-120.35.51a4.5,4.5,0,0,0-3.75,3.4,4.58,4.58,0,0,0,3.29,5.58,4.09,4.09,0,0,0,1.14.14,4.58,4.58,0,1,0-.68-9.12Z\" fill=\"#15143d\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28f7d58c elementor-widget elementor-widget-heading\" data-id=\"28f7d58c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ufkunuzu geni\u015fletin <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12b7836a elementor-widget elementor-widget-text-editor\" data-id=\"12b7836a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00d6nc\u00fc bir kimyasal madde a\u011f\u0131 olarak, daima iddial\u0131 \u00fcreticileri ve tedarik\u00e7ileri kendimize \u00e7ekmeye \u00f6nem veriyoruz. Bir ortak olarak, pan Avrupa ve k\u00fcreselle\u015fmi\u015f da\u011f\u0131t\u0131m a\u011f\u0131n\u0131n bir par\u00e7as\u0131 olman\u0131n avantaj\u0131ndan yararlanacaks\u0131n\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb8faed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb8faed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71a6c9b\" data-id=\"71a6c9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-280d12f elementor-widget elementor-widget-spacer\" data-id=\"280d12f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72e09833 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"72e09833\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54e9b37a\" data-id=\"54e9b37a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-682f8518 elementor-widget elementor-widget-heading\" data-id=\"682f8518\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PlusChem\u2018e kat\u0131lma hakk\u0131nda \u015fimdi daha fazla \u015fey \u00f6\u011frenin!<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f21c029 elementor-button-align-start elementor-widget__width-inherit elementor-mobile-button-align-center elementor-widget elementor-widget-form\" data-id=\"f21c029\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;button_width&quot;:&quot;25&quot;,&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Join PlusChem form\" aria-label=\"Join PlusChem form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"19569\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"f21c029\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"PLUSCHEM\u2019E KATILIN\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"19569\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-name\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tAd\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-email\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tE-posta\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-reason elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-reason\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u0130leti\u015fime ge\u00e7me nedeni\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[reason]\" id=\"form-field-reason\" class=\"elementor-field-textual elementor-size-sm\" required=\"required\">\n\t\t\t\t\t\t\t\t\t<option value=\"No_selection_made\">L\u00fctfen bir se\u00e7enek se\u00e7iniz<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PlusChem&#039;e \u0130\u015f Orta\u011f\u0131 olarak kat\u0131lmak istiyorum\">PlusChem&#039;e \u0130\u015f Orta\u011f\u0131 olarak kat\u0131lmak istiyorum<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"PlusChem&#039;e Tedarik\u00e7i olarak kat\u0131lmak istiyorum\">PlusChem&#039;e Tedarik\u00e7i olarak kat\u0131lmak istiyorum<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-acceptance elementor-col-50 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-acceptance\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u015eartlar\u0131m\u0131z\u0131 kabul etti\u011finizi g\u00f6stermek i\u00e7in bu kutuyu i\u015faretlemelisiniz.\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[acceptance]\" id=\"form-field-acceptance\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\" required=\"required\">\n\t\t\t\t<label for=\"form-field-acceptance\">PlusChem EEIG'nin ilgili i\u00e7erik (haberler ve \u00fcr\u00fcn g\u00fcncellemeleri) ile ilgili olarak benimle ileti\u015fime ge\u00e7mek i\u00e7in bu bilgileri kullanmas\u0131n\u0131 kabul ediyorum.<\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_3c8622e elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_3c8622e\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LcFjvgUAAAAAOdN_9fJU0uam-rkFSgDHMvG6B_q\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-25 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">G\u00f6nder<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b65ac6b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b65ac6b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0b1bf17\" data-id=\"0b1bf17\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb07291 elementor-widget elementor-widget-spacer\" data-id=\"fb07291\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>PlusChem &#8211; Kendini Kan\u0131tlam\u0131\u015f bir Uzmanla \u00c7al\u0131\u015f\u0131n PlusChem d\u00fcnyan\u0131n \u00f6nc\u00fc kimyasal distrib\u00fct\u00f6r a\u011flar\u0131ndan biridir ve bizimle \u00e7al\u0131\u015fmak hem tedarik\u00e7ilere hem de yeni ortaklara bir\u00e7ok avantaj sunuyor. K\u00fcresel olarak 21 \u00fclkede faaliyet g\u00f6stererek, ila\u00e7, g\u0131da, yem, kozmetik, zirai ila\u00e7, end\u00fcstriyel, t\u0131bbi polimer, kaplama, yap\u0131\u015ft\u0131r\u0131c\u0131 ve kau\u00e7uk dahil olmak \u00fczere ana sanayilerde uluslararas\u0131 olarak ortaklar\u0131m\u0131zla \u00e7al\u0131\u015f\u0131yoruz. Gelecek [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16764,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"%%sitetitle%% %%sep%% %%post_title%%","_seopress_titles_desc":"Operating in over 21 countries globally, working with PlusChem offers many advantages for both suppliers and new partners alike.","_seopress_robots_index":"","footnotes":""},"class_list":["post-19569","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages\/19569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/comments?post=19569"}],"version-history":[{"count":0,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages\/19569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/media\/16764"}],"wp:attachment":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/media?parent=19569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}