{"id":19610,"date":"2021-09-06T14:21:52","date_gmt":"2021-09-06T14:21:52","guid":{"rendered":"https:\/\/pluschem.com\/about-us\/our-members\/"},"modified":"2023-01-11T18:04:45","modified_gmt":"2023-01-11T18:04:45","slug":"our-members","status":"publish","type":"page","link":"https:\/\/dev.pluschem.com\/tr\/about-us\/our-members\/","title":{"rendered":"\u00dcyelerimiz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19610\" class=\"elementor elementor-19610 elementor-4387\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6566b7b1 elementor-section-full_width elementor-section-height-min-height elementor-section-items-stretch elementor-section-height-default\" data-id=\"6566b7b1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-304cac61\" data-id=\"304cac61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be17d42 elementor-widget elementor-widget-heading\" data-id=\"be17d42\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/dev.pluschem.com\/about-us\/\">Hakk\u0131nda<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d86f26d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d86f26d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cdca6b\" data-id=\"8cdca6b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bd279 elementor-widget elementor-widget-spacer\" data-id=\"44bd279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e6c7c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2e6c7c1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2ba8059\" data-id=\"2ba8059\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2d5c278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d5c278\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0020494\" data-id=\"0020494\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c2b32d5 elementor-widget elementor-widget-image\" data-id=\"c2b32d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.altichem.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-member-Altichem-logo-300x100-1.png\" class=\"attachment-full size-full wp-image-16395\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da4cb99 elementor-widget elementor-widget-text-editor\" data-id=\"da4cb99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Altichem, bir aile holding \u015firketinin par\u00e7as\u0131 ve Avrupa\u2019da end\u00fcstri sekt\u00f6r\u00fcnde bir kilit oyuncudur. Altichem&#8217;in ba\u015far\u0131s\u0131n\u0131n s\u0131rr\u0131, de\u011fi\u015fmeyen&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c08b5f2 elementor-widget elementor-widget-toggle\" data-id=\"c08b5f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2011\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2011\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2011\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2011\"><p>de\u011ferlerine ba\u011fl\u0131 kalmas\u0131nda ve uzun s\u00fcreli bir gelecek vizyonunda yatmaktad\u0131r.<\/p><p>50 y\u0131ll\u0131k tecr\u00fcbeyle, bu temel prensipler bu aile \u015firketini end\u00fcstri ve kimyasal madde sekt\u00f6rlerinde kilit bir oyuncu yapm\u0131\u015ft\u0131r. Zorluktan keyif almam\u0131z ve geli\u015fim i\u00e7in istikrarl\u0131 bir \u015fekilde hareket etmemiz, m\u00fc\u015fterilerimize yenilik\u00e7i \u00fcr\u00fcn \u00e7\u00f6z\u00fcmleri sunmam\u0131za olanak sa\u011fl\u0131yor.<\/p><p>Kendi antrepo i\u015fletmelerimizle mineral tuzlar\u0131, nadir elementler, pers\u00fclfat ve organik maddelerin ticareti ve da\u011f\u0131t\u0131m\u0131nda uzman\u0131z.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6f51378\" data-id=\"6f51378\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-920127d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"920127d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-614c643\" data-id=\"614c643\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e73b9c8 elementor-widget elementor-widget-image\" data-id=\"e73b9c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.gold-mann.de\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"101\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-member-GoldMann-logo-300x100-1.png\" class=\"attachment-full size-full wp-image-16398\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb96381 elementor-widget elementor-widget-text-editor\" data-id=\"cb96381\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Goldmann Group, \u00c7in&#8217;deki kimyasal maddeler, plastikler ve operasyonlar alanlar\u0131ndaki \u00fc\u00e7 kurulu\u015ftan olu\u015fmaktad\u0131r. 1919\u2019da &#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13aa57d elementor-widget elementor-widget-toggle\" data-id=\"13aa57d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2061\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2061\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2061\"><p>Sidney Goldmann taraf\u0131ndan Almanya, Bielefeld\u2019ta kurulan S. Goldmann, tamamen bir ticari giri\u015fim olarak ba\u015flad\u0131. Temel hedef, ABD\u2019den yerli seramik\/emaye\/cam ve g\u00fcbre end\u00fcstrilerinin ihtiya\u00e7lar\u0131na uygun boraks ve borik asit tedariki \u00fczerineydi.<\/p><p>100 y\u0131ld\u0131r kimyasal madde end\u00fcstrisinde rekabet\u00e7i sat\u0131\u015f ve da\u011f\u0131t\u0131m\u0131n yan\u0131nda ki\u015fisel dan\u0131\u015fmanl\u0131\u011fa, g\u00fcvenilir \u00fcretime ve teslimata kendimizi adad\u0131k.<\/p><p>Uzun s\u00fcreli ulusal ve uluslararas\u0131 tecr\u00fcbeli g\u00fc\u00e7l\u00fc bir ortak olarak bize g\u00fcvenin!<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-714cc19\" data-id=\"714cc19\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bbd2122 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbd2122\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cb50f23\" data-id=\"cb50f23\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-254ad5e elementor-widget elementor-widget-image\" data-id=\"254ad5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.torchiani.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"101\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-member-Torchiani-logo-300x100-1.png\" class=\"attachment-full size-full wp-image-16401\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f92c8b0 elementor-widget elementor-widget-text-editor\" data-id=\"f92c8b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>1928\u2019de Brescia\u2019da Renzo Torchiani taraf\u0131ndan kurulan \u015firket, faaliyetine ev deterjanlar\u0131 \u00fcreterek ba\u015flad\u0131. \u015eirket&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e066a1 elementor-widget elementor-widget-toggle\" data-id=\"9e066a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1651\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1651\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1651\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1651\"><p>sanayi, tar\u0131m ve di\u011fer ekonomi sekt\u00f6rleri i\u00e7in kimyasal maddeleri piyasaya sunarak gittik\u00e7e artan bir \u015fekilde \u00fcretimi geni\u015fletti. \u015eirket \u015fimdi Torchiani ailesinin \u00fc\u00e7\u00fcnc\u00fc ku\u015fa\u011f\u0131 taraf\u0131ndan y\u00f6netiliyor.<\/p><p>Halihaz\u0131rdaKuzey-Orta \u0130talya\u2019y\u0131 kapsayan pazar\u0131n\u0131 ve i\u015fini geni\u015fletme amac\u0131yla son zamanlarda, sat\u0131n almalar ve devralmalarla bir geli\u015fim s\u00fcreci ba\u015flatt\u0131.<\/p><p>Kimyasal madde sanayisinin \u00e7o\u011fu temel sekt\u00f6r\u00fcnde aktif olan Torchiani, ticari ve \u00f6zellikli kimyasallar i\u00e7in Kuzey \u0130talya, Brescia\u2019daki merkezinden ula\u015f\u0131m\/lojistik, antrepo ve pazarlama\/sat\u0131\u015f i\u015fletmeleriyle entegre bir da\u011f\u0131t\u0131m tedarik zinciri sunmaktad\u0131r.<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1626638 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1626638\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a3a05ff\" data-id=\"a3a05ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c0ae2d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0ae2d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-214ec9f\" data-id=\"214ec9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58f04c7 elementor-widget elementor-widget-image\" data-id=\"58f04c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ncc.ie\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"101\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-member-NCC-logo-300x100-1.png\" class=\"attachment-full size-full wp-image-16404\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3886401 elementor-widget elementor-widget-text-editor\" data-id=\"3886401\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Denis Looney taraf\u0131ndan 1969\u2019da kurulan The National Chemical Company (NCC), \u00f6nc\u00fc bir ham madde ve tedarik&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98de220 elementor-widget elementor-widget-toggle\" data-id=\"98de220\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1601\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1601\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1601\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1601\"><p>uzman\u0131d\u0131r. Denis\u2019in o\u011flu Alan Looney 1987\u2019de Y\u00f6netim M\u00fcd\u00fcr\u00fc olarak g\u00f6revi devrald\u0131 ve o zamandan beri \u015firketi y\u00f6netiyor.<\/p><p>Ba\u015flang\u0131\u00e7ta geleneksel end\u00fcstri \u00fcr\u00fcnleri \u00fczerine odaklanan NCC, 1990\u2019larda kapsam\u0131n\u0131 geni\u015fletti ve \u015fimdi \u00e7ok \u00e7e\u015fitli pazarlar\u0131n yan\u0131nda \u0130rlanda, Birle\u015fik Krall\u0131k ve uluslararas\u0131 olarak hizmet veren bir portf\u00f6ye sahiptir.<\/p><p>\u0130la\u00e7 sanayi, t\u0131bbi polimer, g\u0131da ve end\u00fcstri sekt\u00f6rlerinin malzemeleri ve bile\u015fenlerinin geni\u015f bir yelpazesini tedarik ediyor. NCC\u2019nin m\u00fckemmel ba\u015far\u0131 ge\u00e7mi\u015fi ve kurum i\u00e7i uzmanlar\u0131 m\u00fc\u015fterilerin s\u00fcrekli uygun \u00fcr\u00fcnleri, sol\u00fcsyonlar\u0131 ve tam tedarik zinciri izlenebilirli\u011fini ve en y\u00fcksek global standartlar\u0131n\u0131 kar\u015f\u0131layan hizmetleri almalar\u0131n\u0131 garanti ediyor.<\/p><p>NCC\u2019nin teklifleri, m\u00fc\u015fterilerin ihtiya\u00e7lar\u0131yla ve hedefleriyle uyum sa\u011flayacak \u015fekilde \u00f6zellikle tasarlanm\u0131\u015ft\u0131r. Malzemeleri size zaman\u0131nda ve eksiksiz ula\u015ft\u0131rmaya odaklanm\u0131\u015f ve i\u015fine adanm\u0131\u015f ki\u015filer taraf\u0131ndan i\u015fletilen g\u00fc\u00e7l\u00fc bir kalite y\u00f6netim sistemine sahiptir. NCC, lojistik \u00e7\u00f6z\u00fcmlerin yan\u0131nda kaynak bulmadan tedarik zinciri y\u00f6netimine kadar t\u00fcm y\u00f6nleri kapsayan tam bir hizmet paketi sunuyor.<\/p><p>2008\u2019de NCC ve ham madde i\u015fleyicisi PVC\u2018nin \u00f6nceki orta\u011f\u0131 olan, Kilbeggan, Country Westmeath merkezli, t\u0131bbi polimer bile\u015fenlerini i\u015flemekte uzmanla\u015fan ve ISO 13485 T\u0131bbi Cihaz \u00dcretimi standard\u0131 sertifikal\u0131 Associated Plastics of Ireland Ltd. Innovative Polymer Compounds (IPC) aras\u0131nda bir ortak giri\u015fim kuruldu.<\/p><p>NCC, ISO 9001 Sertifikal\u0131d\u0131r: 2015\u2019te bir Repak \u00fcyesi oldu ve \u0130yi Ticaret ve Da\u011f\u0131t\u0131m Uygulamalar\u0131n\u0131 kapsayan Sorumlu Bak\u0131m Programlar\u0131n\u0131(GTDP) hayata ge\u00e7irdi. NCC, 2014\u2019ten beri SQAS taraf\u0131ndan de\u011ferlendirilen bir \u015firkettir ve Deloitte En \u0130yi Y\u00f6netilen \u015eirket olmas\u0131 da dahil d\u00fczenli olarak end\u00fcstri \u00f6d\u00fclleri almaktad\u0131r.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-659f093\" data-id=\"659f093\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d8d63e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d8d63e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-0a8c60d\" data-id=\"0a8c60d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36dff1b elementor-widget elementor-widget-image\" data-id=\"36dff1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.grupbarcelonesa.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-member-barcelonesa-logo-300x100-1.png\" class=\"attachment-full size-full wp-image-16407\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f3e0a5 elementor-widget elementor-widget-text-editor\" data-id=\"9f3e0a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Barcelonesa\u2018da sadece bir tedarik\u00e7i veya kimyasal madde uzman\u0131ndan daha fazlas\u0131y\u0131z.<br \/>Ancak, sa\u011flam ve s\u00fcrekli ili\u015fkiler&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc42104 elementor-widget elementor-widget-toggle\" data-id=\"cc42104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2141\"><p>kurarak b\u00fcy\u00fcyebilece\u011fimize ve bir \u015firket, insanlar ve toplum olarak ilerleyebilece\u011fimize inan\u0131yoruz. Bu nedenle, amac\u0131m\u0131z verimlili\u011fi, g\u00fcvenilirli\u011fi, sorumlulu\u011fu ve s\u00fcrd\u00fcr\u00fclebilirli\u011fi t\u00fcm faaliyet sekt\u00f6rlerinde en \u00fcst d\u00fczeye \u00e7\u0131karacak kimyasal \u00e7\u00f6z\u00fcmleri garanti etmek i\u00e7in m\u00fc\u015fterilerimiz ve ortaklar\u0131m\u0131zla yak\u0131ndan i\u015f birli\u011fi yapmakt\u0131r.<\/p><p>Bizim i\u00e7in ba\u015far\u0131n\u0131n anahtar\u0131 sa\u011flam ve s\u00fcrekli bir ili\u015fki kurarak, ekibinizle birlikte \u00e7al\u0131\u015farak ve her payda\u015f ile i\u015f birli\u011fi yaparak kendimizi sizin \u015firketinizin ger\u00e7ekli\u011fiyle entegre etmektir. Bu, bizim verimlili\u011fi, g\u00fcvenilirli\u011fi, sorumlulu\u011fu ve s\u00fcrd\u00fcr\u00fclebilirli\u011fi en \u00fcst d\u00fczeye \u00e7\u0131karan kimyasal \u00e7\u00f6z\u00fcmleri garanti etme form\u00fcl\u00fcm\u00fczd\u00fcr.<\/p><p>Halihaz\u0131rda 50\u2019den fazla \u00fclkede 2,000\u2019den fazla m\u00fc\u015fteriye yard\u0131mc\u0131 olan bir form\u00fcl.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-555f21e\" data-id=\"555f21e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-add642b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"add642b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-aae8816\" data-id=\"aae8816\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb59302 elementor-widget elementor-widget-image\" data-id=\"bb59302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/afriglobalonline.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/07\/PlusChem-Member-AfriGlobal-300x100-1.png\" class=\"attachment-full size-full wp-image-16455\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-05f0979 elementor-widget elementor-widget-text-editor\" data-id=\"05f0979\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Afriglobal Commodities (AGC), Afrika merkezli \u00f6nc\u00fc bir ticaret ve da\u011f\u0131t\u0131m kurulu\u015fudur. 1988\u2019de Nijerya\u2019da&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ab612b elementor-widget elementor-widget-toggle\" data-id=\"3ab612b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-6151\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-6151\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-6151\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-6151\"><p>kurulan AGC, \u015fimdi Dubai merkezlidir. Da\u011f\u0131t\u0131m faaliyetlerimiz Afrika\u2019y\u0131 ve Orta Do\u011fu\u2019yu kapsamaktad\u0131r.<\/p><p>Y\u0131ll\u0131k 4000 adet 20\u201dlik konteyneri a\u015fan i\u015flem hacmiyle AGC, ayn\u0131 zamanda b\u00f6lgedeki en h\u0131zl\u0131 b\u00fcy\u00fcyen ticaret ve da\u011f\u0131t\u0131m i\u015fletmelerinden biridir. Geni\u015f \u00fcr\u00fcn yelpazemiz \u2013 150\u2019den fazla stok kodu \u2013 Afrika\u2019da en fazla ticareti yap\u0131lan kimyasal \u00fcr\u00fcnlerin %70\u2019ten fazlas\u0131n\u0131 kapsamaktad\u0131r.<br \/><br \/><\/p><p>En iyi kaliteyi sunan 40\u2019tan fazla b\u00fcy\u00fck k\u00fcresel tedarik\u00e7iden olu\u015fan tedarik taban\u0131m\u0131z, b\u00f6lgede uluslararas\u0131 \u00fcr\u00fcnlerinfiyat\u0131n\u0131 rekabet\u00e7i bir \u015fekilde belirlemi\u015ftir. Ticaret yakla\u015f\u0131m\u0131m\u0131z, da\u011f\u0131t\u0131m anlay\u0131\u015f\u0131yla y\u00f6netilmektedir\u2013 derin m\u00fc\u015fteri anlay\u0131\u015f\u0131 &amp; ili\u015fkileri geli\u015ftirmeyi ama\u00e7l\u0131yoruz. Bu, iste\u011fe g\u00f6re uyarlanm\u0131\u015f \u00fcr\u00fcnler &amp; m\u00fc\u015fterilerimizin \u00f6zel ihtiya\u00e7lar\u0131n\u0131 kar\u015f\u0131lamay\u0131 hedefleyen y\u00fcksek kaliteli hizmetler sa\u011flamam\u0131za olanak tan\u0131maktad\u0131r. Nijerya merkezli g\u00fc\u00e7l\u00fc teknik servis ekibimiz m\u00fc\u015fterilerimizin \u00fcr\u00fcnleri uygun maliyetli optimizasyonla kullanmas\u0131n\u0131 destekliyor.<br \/><br \/>Vizyonumuz Pan-Afrika Kimyasal Maddeleri ve Ba\u011fl\u0131 \u00dcr\u00fcnleri da\u011f\u0131t\u0131m ticareti \u00f6nc\u00fc grubu olmakt\u0131r. De\u011ferlerimiz, d\u00fcr\u00fcstl\u00fck, bireylere sayg\u0131, m\u00fc\u015fteri ba\u015far\u0131s\u0131 yakalama tutkusu ve t\u00fcm faaliyetlerimizde uzun vadeli d\u00fc\u015f\u00fcnmektir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-870cfc1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"870cfc1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0eb51c9\" data-id=\"0eb51c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9ba546e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ba546e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5881a9c\" data-id=\"5881a9c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-389123c elementor-widget elementor-widget-image\" data-id=\"389123c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"http:\/\/ketsincr.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2022\/10\/ketsin-logo-new-300x100-1.jpg\" class=\"attachment-full size-full wp-image-19546\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bb6a0e elementor-widget elementor-widget-text-editor\" data-id=\"0bb6a0e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Orta Amerika, Kosta Rika\u2019da bulunan Ketsin, daima g\u00fcvenlik, hijyen ve m\u00fc\u015fteriler, personel, tedarik\u00e7iler, toplum ve \u00e7evreye kar\u015f\u0131 sorumlulu\u011fu&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f6c8f05 elementor-widget elementor-widget-toggle\" data-id=\"f6c8f05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2581\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2581\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2581\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2581\"><p>dikkate alarak yasal me\u015fruiyet, hizmet kalitesi ve \u00fcr\u00fcnlerimizin sorumlu da\u011f\u0131t\u0131m\u0131 \u00e7er\u00e7evesinde \u00e7al\u0131\u015fmaktad\u0131r.<\/p><p>Piyasaya sundu\u011fumuz \u00f6zellikli \u00fcr\u00fcnler ve ham maddelerde piyasaya y\u00fcksek seviye hizmeti getirerek profesyonel ve sorumlu bir \u015fekilde i\u015finizi geli\u015ftirmek i\u00e7in Orta Amerika ve Meksika \u00e7ap\u0131nda hizmetlerimizi sa\u011flayabiliyoruz.<\/p><p>Polimerler, boya &amp; kaplama, g\u0131da katk\u0131 maddeleri, \u00e7\u00f6z\u00fcc\u00fcler, \u00f6zellikli \u00fcr\u00fcnler ve dezenfektanlar \u00fczerine yo\u011funla\u015f\u0131yoruz.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-67cb0e3\" data-id=\"67cb0e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c3acb2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c3acb2d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b9a0791\" data-id=\"b9a0791\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a13da52 elementor-widget elementor-widget-image\" data-id=\"a13da52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.trc-ag.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-Member-TRC-300x100-1.png\" class=\"attachment-full size-full wp-image-16413\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6092afe elementor-widget elementor-widget-text-editor\" data-id=\"6092afe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kanada, Ontario, Burlington\u2019da bulunan ve Wiggins ailesi taraf\u0131ndan kurulan Thames River Chemials (TRC), Kuzey Amerika&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f93f3a elementor-widget elementor-widget-toggle\" data-id=\"2f93f3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4981\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4981\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4981\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4981\"><p>genelinde ve global kanallarla \u00e7e\u015fitli end\u00fcstrilerde 2006\u2019dan beri gururla hizmet vermektedir.<\/p><p>O zamandan beri TRC, g\u00fcnl\u00fck i\u015flemlerinde ve m\u00fc\u015fteri oda\u011f\u0131nda \u00f6zel uyarlanm\u0131\u015f ve hizmet odakl\u0131 bir yakla\u015f\u0131m\u0131n en \u00fcstte tutuldu\u011fundan emin olmak i\u00e7in istikrarl\u0131, d\u00fczenli bir \u00e7abay\u0131 s\u00fcrd\u00fcrd\u00fc. Kendini i\u015fine adam\u0131\u015f ekibiyle ve 2,500\u2019den fazla m\u00fc\u015fterili s\u00fcrekli b\u00fcy\u00fcyen taban\u0131yla TRC, on y\u0131l \u00f6nceki ba\u015flang\u0131c\u0131ndan bu yana ilerleme kaydetti.<\/p><p>\u015eimdiye kadar, TRC\u2019nin kapasitesi b\u00fcy\u00fcrken ve ufku geni\u015flerken, bu belirgin m\u00fc\u015fteri odakl\u0131 yakla\u015f\u0131m bozulmadan devam etmektedir. Thames River Chemical, sadece talep \u00fczerine tedarik ve end\u00fcstri \u00e7\u00f6z\u00fcmleri de\u011fil ayn\u0131 zamanda belirgin olarak ki\u015fisel ve kendini i\u015fe adam\u0131\u015f bir yakla\u015f\u0131m da sunuyor.<\/p><p>Bug\u00fcn, TRC 100\u2019den fazla tedarik\u00e7i ile verimli ili\u015fkiler s\u00fcrd\u00fcr\u00fcyor ve \u201cailesi\u201d \u2013 her biri kendi e\u015fsiz pazar bilgisini, teknik uzmanl\u0131\u011f\u0131n\u0131, lojistik uzmanl\u0131\u011f\u0131n\u0131 ve m\u00fc\u015fteri merkezli oda\u011f\u0131n\u0131 masaya getiren \u2013 50\u2019den fazla end\u00fcstri profesyonelini b\u00fcnyesinde bar\u0131nd\u0131r\u0131yor. Gelecek end\u00fcstri ihtiyac\u0131n\u0131z i\u00e7in, size do\u011fru \u00e7\u00f6z\u00fcm\u00fc bulal\u0131m. <a href=\"http:\/\/www.trc-corp.com\">www.trc-corp.com<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d5c6353\" data-id=\"d5c6353\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd22069 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd22069\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-83616ef\" data-id=\"83616ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-105cdc9 elementor-widget elementor-widget-image\" data-id=\"105cdc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.proteachemicals.co.za\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-Member-Protea-300x100-1.png\" class=\"attachment-full size-full wp-image-16419\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b72a13 elementor-widget elementor-widget-text-editor\" data-id=\"0b72a13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Protea Chemicals, \u00f6zellikli kimyasal \u00fcr\u00fcnlerin ve madencilikte, tar\u0131mda ve kimyasal madde sekt\u00f6rlerinde kullan\u0131lan hizmetlerin JSE listesinde ..<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44898a4 elementor-widget elementor-widget-toggle\" data-id=\"44898a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-7181\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7181\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7181\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7181\"><p>yer alan geni\u015f yelpazeli tedarik\u00e7isi Omnia Group\u2019un bir \u00fcyesidir.<\/p><p>\u00d6zellikli ve i\u015flevsel kimyasallar\u0131n g\u00fcvenilir bir da\u011f\u0131t\u0131c\u0131s\u0131 ve \u00fcreticisiyiz. 60\u2019tan fazla y\u0131ld\u0131r, g\u0131dadan tar\u0131ma, ula\u015f\u0131mdan tekstile neredeyse g\u00fcnl\u00fck ya\u015fam\u0131n her boyutunun bir par\u00e7as\u0131 olduk. G\u00fcney Afrika men\u015feli ve yerli miras\u0131yla gurur duyan Omnia Group\u2019un bir \u00fcyesiyiz.<\/p><p>Afrika\u2019da Cape Town, Johannesburg\u2019ta ve Durban\u2019da tesisleriyle ve aktarma merkezleriyle entegre bir tedarik zinciri, lojistik ve da\u011f\u0131t\u0131m i\u015fletmemiz var.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29566e6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"29566e6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-426e6d5\" data-id=\"426e6d5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-66e53e2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66e53e2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c6819b7\" data-id=\"c6819b7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-578498e elementor-widget elementor-widget-image\" data-id=\"578498e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.anp.co.jp\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-Member-logo-ANP-300x100-1.png\" class=\"attachment-full size-full wp-image-16425\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53086e8 elementor-widget elementor-widget-text-editor\" data-id=\"53086e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Andoh Parachemie Co., Ltd., bir parafin, ya\u011f ve \u015feker toptanc\u0131s\u0131 olarak Owari Nagoya\u2019da kuruldu. Kurulu\u015fundan beri&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6994ea8 elementor-widget elementor-widget-toggle\" data-id=\"6994ea8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1101\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1101\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1101\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1101\"><p>Andoh Parachemie Co., Ltd., g\u00fcvene dayal\u0131 bir petrokimya \u00fcr\u00fcnleri ticaret \u015firketi olarak ilerleme g\u00f6sterdi ve \u015fimdi 1,900\u2019den fazla i\u015f orta\u011f\u0131na sahiptir.<\/p><p>Japonya\u2019da 30\u2019dan fazla noktada stok lojistik \u00fcslerinden olu\u015fan kapsaml\u0131 bir teslimat a\u011f\u0131na sahip olan bir pazarlama ve kalite kontrol yap\u0131s\u0131 in\u015fa ettik.<\/p><p>Japonya&#8217;daki i\u015fimizi geli\u015ftirmeye devam etmenin yan\u0131nda \u00c7in\u2019de de i\u015fimizi s\u00fcrekli geli\u015ftiriyoruz.<\/p><p>\u00dcretim deniza\u015f\u0131r\u0131 ilerlemeye devam ettik\u00e7e, petrokimya tedarik\u00e7ilerimizi \u00e7e\u015fitlendirerek gelecekte ba\u015far\u0131l\u0131 olmaya devam edecek olan daha k\u00fcresel bir \u015firkete d\u00f6n\u00fc\u015febilece\u011fimize inan\u0131yoruz.<\/p><p>Petrokimya \u00fcr\u00fcnleriyle u\u011fra\u015ft\u0131\u011f\u0131m\u0131z i\u00e7in kurumsal g\u00fcc\u00fcm\u00fczle m\u00fc\u015fteri taleplerini dinlemeye ve onlar\u0131n ihtiya\u00e7lar\u0131n\u0131 tamam\u0131yla anlamaya zaman ay\u0131rarak problemleri \u00e7\u00f6z\u00fcyoruz, b\u00f6ylece biz ve ortaklar\u0131m\u0131z birlikte b\u00fcy\u00fcyebiliyoruz.<\/p><p>Hedefimiz gelecekte de\u011fer \u00fcreten bir kurumsal i\u015fletmeye d\u00f6n\u00fc\u015fmeye devam etmek. Ayr\u0131ca, h\u0131zl\u0131 de\u011fi\u015fen global bir ortamda, t\u00fcm problemlere verimli \u015fekilde yan\u0131t vermeyi ve yeni zorluklar\u0131n \u00fcstesinden gelmeyi ama\u00e7l\u0131yoruz.<\/p><p>Gelecek hedefimiz, ortaklar\u0131m\u0131z\u0131n hayallerini ger\u00e7ekle\u015ftirmelerine yard\u0131m etmek i\u00e7in gelece\u011fe bir k\u00f6pr\u00fc olman\u0131n yan\u0131nda, m\u00fc\u015fterilerimizin ihtiya\u00e7lar\u0131n\u0131 kar\u015f\u0131lamaya devam etmek ve geleneksel bir kimyasal madde ticareti \u015firketinden \u00fcretim kabiliyetleri ve global bir kapsam\u0131 olan bir \u015firkete d\u00f6n\u00fc\u015fmektir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d743e20\" data-id=\"d743e20\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a2e303 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a2e303\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-2f0d08b\" data-id=\"2f0d08b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ede0a61 elementor-widget elementor-widget-image\" data-id=\"ede0a61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/chemetindia.com\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"101\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/06\/PlusChem-Member-Chemet-300x100-1.png\" class=\"attachment-full size-full wp-image-16431\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b6c919 elementor-widget elementor-widget-text-editor\" data-id=\"5b6c919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chemet was founded by Mr. K.B Chemet, Bay K.B Sanghvi taraf\u0131ndan 1968\u2019de kuruldu ve Hindistan\u2019daki en eski ve en b\u00fcy\u00fck kimyasal madde pazarlama i\u015fletmelerinden biridir&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-567f171 elementor-widget elementor-widget-toggle\" data-id=\"567f171\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-9061\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-9061\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-9061\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-9061\"><p>\u00c7o\u011fu kimyasal pazar sekt\u00f6r\u00fcnde aktif, y\u00fcksek d\u00fczeyde kapsaml\u0131 bir \u015firkettir.<\/p><p>Chemet&#8217;in iki faaliyeti, ana kimyasal ham maddeleri Hindistan alt k\u0131tas\u0131na ithal etmeyi ve toplamda 80 \u00e7al\u0131\u015fan n\u00fcfusuyla Hindistan d\u0131\u015f\u0131ndaki m\u00fc\u015fteriler i\u00e7in tedarik orta\u011f\u0131 olarak rol almay\u0131 kaps\u0131yor, ayr\u0131ca merkez ofisleri Bombay\u2019da olan Chemet, Hindistan\u2019da pek \u00e7ok b\u00fcy\u00fck\/metropol \u015fehirde ofislere sahiptir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-30f4d0b\" data-id=\"30f4d0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-69ec218 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"69ec218\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8b7e757\" data-id=\"8b7e757\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab0a69a elementor-widget elementor-widget-image\" data-id=\"ab0a69a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/chemitron.co.il\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/dev.pluschem.com\/wp-content\/uploads\/2021\/10\/chemitron-logo-300x100-1.jpg\" class=\"attachment-full size-full wp-image-16866\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5ee8a elementor-widget elementor-widget-text-editor\" data-id=\"6f5ee8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chemitron \u015eirketler Grubunun CEO\u2019su, Bay Usi Ron, Chemitron Ltd.\u2019yi Ocak 1991&#8230;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e508bb elementor-widget elementor-widget-toggle\" data-id=\"2e508bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-4851\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-4851\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Devam\u0131n\u0131 oku<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-4851\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-4851\"><p>1991\u2019de gruptaki ilk \u015firket olarak kurdu.<\/p><p>Kimyasal madde i\u015finde 50 y\u0131la yak\u0131n tecr\u00fcbeye sahip olan Bay Ron, \u015firketi \u015fimdi y\u00f6netim m\u00fcd\u00fcr\u00fc olan o\u011flu Bay Guy Ron ile birlikte y\u00f6netiyor. \u015eirket \u015fimdi, 1880\u2019e dayanan kimyasal madde tacirlerinin be\u015f nesillik se\u00e7kin miras\u0131n\u0131 temsil ediyor.<\/p><p>Chemitron\u2019un ana faaliyeti, kimyasal madde alanlar\u0131ndaki yabanc\u0131 \u015firketlerin \u00fcr\u00fcnlerini sunma ve da\u011f\u0131t\u0131m yapma etraf\u0131nda odaklan\u0131yor ve daima yerel pazar i\u00e7in yeni tedarik kaynaklar\u0131 aray\u0131\u015f\u0131ndalar.<\/p><p>Chemitron \u015eirketler Grubu, \u0130srail Ticaret Odalar\u0131 Federasyonu, \u0130srail-Alman Ticaret &amp; Sanayi Odas\u0131 ve \u0130srail-\u00dcrd\u00fcn Ticaret &amp; Sanayi Odas\u0131 \u00fcyesidir.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-613144d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"613144d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5126e21\" data-id=\"5126e21\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-665af13 elementor-widget elementor-widget-spacer\" data-id=\"665af13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6db454b elementor-section-content-middle animated-fast elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6db454b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_tablet&quot;:&quot;none&quot;,&quot;animation_mobile&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5fbbdef5\" data-id=\"5fbbdef5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;,&quot;animation_delay&quot;:250}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3622ddeb elementor-section-height-min-height elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"3622ddeb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_tablet&quot;:&quot;fadeIn&quot;,&quot;animation_mobile&quot;:&quot;slideInDown&quot;,&quot;shape_divider_top&quot;:&quot;opacity-tilt&quot;}\">\n\t\t\t\t\t<div class=\"elementor-shape elementor-shape-top\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 2600 131.1\" preserveAspectRatio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0 0L2600 0 2600 69.1 0 0z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.5\" d=\"M0 0L2600 0 2600 69.1 0 69.1z\"\/>\n\t<path class=\"elementor-shape-fill\" style=\"opacity:0.25\" d=\"M2600 0L0 0 0 130.1 2600 69.1z\"\/>\n<\/svg>\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-41b05db4\" data-id=\"41b05db4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dd9e342 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5dd9e342\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInLeft&quot;,&quot;_animation_delay&quot;:500,&quot;_animation_mobile&quot;:&quot;slideInRight&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u015eu anda yeni \u00fcyeler ar\u0131yoruz. Bug\u00fcn bize ula\u015f\u0131n.<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-788b63c6\" data-id=\"788b63c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ca158b6 elementor-align-left elementor-mobile-align-center elementor-widget-mobile__width-auto elementor-tablet-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1ca158b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;slideInRight&quot;,&quot;_animation_delay&quot;:250,&quot;_animation_mobile&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/dev.pluschem.com\/tr\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Evet, daha fazlas\u0131n\u0131 bilmek istiyorum<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9a5303d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9a5303d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b90536e\" data-id=\"b90536e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-020a5de elementor-widget elementor-widget-spacer\" data-id=\"020a5de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Hakk\u0131nda Altichem, bir aile holding \u015firketinin par\u00e7as\u0131 ve Avrupa\u2019da end\u00fcstri sekt\u00f6r\u00fcnde bir kilit oyuncudur. Altichem&#8217;in ba\u015far\u0131s\u0131n\u0131n s\u0131rr\u0131, de\u011fi\u015fmeyen&#8230; Devam\u0131n\u0131 oku de\u011ferlerine ba\u011fl\u0131 kalmas\u0131nda ve uzun s\u00fcreli bir gelecek vizyonunda yatmaktad\u0131r. 50 y\u0131ll\u0131k tecr\u00fcbeyle, bu temel prensipler bu aile \u015firketini end\u00fcstri ve kimyasal madde sekt\u00f6rlerinde kilit bir oyuncu yapm\u0131\u015ft\u0131r. Zorluktan keyif almam\u0131z ve geli\u015fim i\u00e7in istikrarl\u0131 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16872,"parent":19557,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"%%sitetitle%% %%sep%% %%post_title%%","_seopress_titles_desc":"PlusChem in an independent broker, enabling working relationships for both manufacturers and distributors. Find out more about our members here.","_seopress_robots_index":"","footnotes":""},"class_list":["post-19610","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages\/19610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/comments?post=19610"}],"version-history":[{"count":0,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages\/19610\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/pages\/19557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/media\/16872"}],"wp:attachment":[{"href":"https:\/\/dev.pluschem.com\/tr\/wp-json\/wp\/v2\/media?parent=19610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}